{"id":861,"date":"2024-10-21T15:14:14","date_gmt":"2024-10-21T15:14:14","guid":{"rendered":"https:\/\/racoeseforragenscastanheira.com\/?post_type=product&#038;p=861"},"modified":"2025-02-03T12:24:07","modified_gmt":"2025-02-03T12:24:07","slug":"tesoura-de-poda-tradicional","status":"publish","type":"product","link":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/","title":{"rendered":"TESOURA DE PODA TRADICIONAL"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<h4><span style=\"font-weight: 400;\">Tesoura de Podar Tradicional com a l\u00e2mina feita em a\u00e7o de carbono, com uma dimens\u00e3o de 220mm.<\/span><\/h4>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">\n<h4><span style=\"font-weight: 400;\">Tesoura de poda tradicional com l\u00e2mina em a\u00e7o carbono.<\/span><\/h4>\n<\/li>\n<\/ul>","protected":false},"featured_media":862,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":{"0":"post-861","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-horta-jardim","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TESOURA DE PODA TRADICIONAL - racoes e forragens castanheira<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TESOURA DE PODA TRADICIONAL - racoes e forragens castanheira\" \/>\n<meta property=\"og:description\" content=\"Tesoura de Podar Tradicional com a l\u00e2mina feita em a\u00e7o de carbono, com uma dimens\u00e3o de 220mm.    Tesoura de poda tradicional com l\u00e2mina em a\u00e7o carbono.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/\" \/>\n<meta property=\"og:site_name\" content=\"racoes e forragens castanheira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/racoeseforragenscastanheira\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-03T12:24:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-85.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/en\\\/product\\\/tesoura-de-poda-tradicional\\\/\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/en\\\/product\\\/tesoura-de-poda-tradicional\\\/\",\"name\":\"TESOURA DE PODA TRADICIONAL - racoes e forragens castanheira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/en\\\/product\\\/tesoura-de-poda-tradicional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/en\\\/product\\\/tesoura-de-poda-tradicional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Copia-de-Design-sem-nome-85.png\",\"datePublished\":\"2024-10-21T15:14:14+00:00\",\"dateModified\":\"2025-02-03T12:24:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/en\\\/product\\\/tesoura-de-poda-tradicional\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/en\\\/product\\\/tesoura-de-poda-tradicional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/en\\\/product\\\/tesoura-de-poda-tradicional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Copia-de-Design-sem-nome-85.png\",\"contentUrl\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Copia-de-Design-sem-nome-85.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/en\\\/product\\\/tesoura-de-poda-tradicional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TESOURA DE PODA TRADICIONAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#website\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\",\"name\":\"racoes e forragens castanheira\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#organization\",\"name\":\"racoes e forragens castanheira\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lightgoldenrodyellow-dugong-899059.hostingersite.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image003-e1726606072123.jpg\",\"contentUrl\":\"https:\\\/\\\/lightgoldenrodyellow-dugong-899059.hostingersite.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image003-e1726606072123.jpg\",\"width\":640,\"height\":405,\"caption\":\"racoes e forragens castanheira\"},\"image\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/racoeseforragenscastanheira\",\"https:\\\/\\\/www.instagram.com\\\/racoes_e_forragens_castanheira\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TESOURA DE PODA TRADICIONAL - racoes e forragens castanheira","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/","og_locale":"en_GB","og_type":"article","og_title":"TESOURA DE PODA TRADICIONAL - racoes e forragens castanheira","og_description":"Tesoura de Podar Tradicional com a l\u00e2mina feita em a\u00e7o de carbono, com uma dimens\u00e3o de 220mm.    Tesoura de poda tradicional com l\u00e2mina em a\u00e7o carbono.","og_url":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/","og_site_name":"racoes e forragens castanheira","article_publisher":"https:\/\/www.facebook.com\/racoeseforragenscastanheira","article_modified_time":"2025-02-03T12:24:07+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-85.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/","url":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/","name":"TESOURA DE PODA TRADICIONAL - racoes e forragens castanheira","isPartOf":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/#primaryimage"},"image":{"@id":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/#primaryimage"},"thumbnailUrl":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-85.png","datePublished":"2024-10-21T15:14:14+00:00","dateModified":"2025-02-03T12:24:07+00:00","breadcrumb":{"@id":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/#primaryimage","url":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-85.png","contentUrl":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-85.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/tesoura-de-poda-tradicional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/racoeseforragenscastanheira.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/racoeseforragenscastanheira.com\/shop\/"},{"@type":"ListItem","position":3,"name":"TESOURA DE PODA TRADICIONAL"}]},{"@type":"WebSite","@id":"https:\/\/racoeseforragenscastanheira.com\/#website","url":"https:\/\/racoeseforragenscastanheira.com\/","name":"racoes e forragens castanheira","description":"","publisher":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/racoeseforragenscastanheira.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/racoeseforragenscastanheira.com\/#organization","name":"racoes e forragens castanheira","url":"https:\/\/racoeseforragenscastanheira.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/racoeseforragenscastanheira.com\/#\/schema\/logo\/image\/","url":"https:\/\/lightgoldenrodyellow-dugong-899059.hostingersite.com\/wp-content\/uploads\/2025\/01\/image003-e1726606072123.jpg","contentUrl":"https:\/\/lightgoldenrodyellow-dugong-899059.hostingersite.com\/wp-content\/uploads\/2025\/01\/image003-e1726606072123.jpg","width":640,"height":405,"caption":"racoes e forragens castanheira"},"image":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/racoeseforragenscastanheira","https:\/\/www.instagram.com\/racoes_e_forragens_castanheira\/"]}]}},"_links":{"self":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product\/861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/comments?post=861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/media\/862"}],"wp:attachment":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/media?parent=861"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_brand?post=861"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_cat?post=861"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_tag?post=861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}