{"id":835,"date":"2024-10-21T14:33:21","date_gmt":"2024-10-21T14:33:21","guid":{"rendered":"https:\/\/racoeseforragenscastanheira.com\/?post_type=product&#038;p=835"},"modified":"2026-03-25T16:15:20","modified_gmt":"2026-03-25T16:15:20","slug":"abano-em-palha-com-cabo-em-madeira","status":"publish","type":"product","link":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/abano-em-palha-com-cabo-em-madeira\/","title":{"rendered":"Abano em palha com cabo em madeira"},"content":{"rendered":"<p data-start=\"136\" data-end=\"462\">O <strong data-start=\"138\" data-end=\"176\">Abano em Palha com Cabo em Madeira<\/strong> \u00e9 a ferramenta perfeita para quem busca conforto e praticidade na hora de espantar o calor ou auxiliar em ambientes mais quentes. Com um design r\u00fastico e natural, o abano possui um cabo em madeira resistente e confort\u00e1vel para manuseio, proporcionando durabilidade e facilidade no uso.<\/p>\n<p data-start=\"464\" data-end=\"769\">","protected":false},"excerpt":{"rendered":"<p data-start=\"136\" data-end=\"462\">O <strong data-start=\"138\" data-end=\"176\">Abano em Palha com Cabo em Madeira<\/strong> \u00e9 a ferramenta perfeita para quem busca conforto e praticidade na hora de espantar o calor ou auxiliar em ambientes mais quentes. Com um design r\u00fastico e natural, o abano possui um cabo em madeira resistente e confort\u00e1vel para manuseio, proporcionando durabilidade e facilidade no uso.<\/p>\n<p data-start=\"464\" data-end=\"769\">","protected":false},"featured_media":836,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[97],"product_tag":[],"class_list":{"0":"post-835","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-diversos","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abano em palha com cabo em madeira - racoes e forragens castanheira<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/racoeseforragenscastanheira.com\/en\/product\/abano-em-palha-com-cabo-em-madeira\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abano em palha com cabo em madeira - racoes e forragens castanheira\" \/>\n<meta property=\"og:description\" content=\"O Abano em Palha com Cabo em Madeira \u00e9 a ferramenta perfeita para quem busca conforto e praticidade na hora de espantar o calor ou auxiliar em ambientes mais quentes. Com um design r\u00fastico e natural, o abano possui um cabo em madeira resistente e confort\u00e1vel para manuseio, proporcionando durabilidade e facilidade no uso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/racoeseforragenscastanheira.com\/en\/product\/abano-em-palha-com-cabo-em-madeira\/\" \/>\n<meta property=\"og:site_name\" content=\"racoes e forragens castanheira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/racoeseforragenscastanheira\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T16:15:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-78.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/abano-em-palha-com-cabo-em-madeira\\\/\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/abano-em-palha-com-cabo-em-madeira\\\/\",\"name\":\"Abano em palha com cabo em madeira - racoes e forragens castanheira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/abano-em-palha-com-cabo-em-madeira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/abano-em-palha-com-cabo-em-madeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Copia-de-Design-sem-nome-78.png\",\"datePublished\":\"2024-10-21T14:33:21+00:00\",\"dateModified\":\"2026-03-25T16:15:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/abano-em-palha-com-cabo-em-madeira\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/abano-em-palha-com-cabo-em-madeira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/abano-em-palha-com-cabo-em-madeira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Copia-de-Design-sem-nome-78.png\",\"contentUrl\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Copia-de-Design-sem-nome-78.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/abano-em-palha-com-cabo-em-madeira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abano em palha com cabo em madeira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#website\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\",\"name\":\"racoes e forragens castanheira\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#organization\",\"name\":\"racoes e forragens castanheira\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lightgoldenrodyellow-dugong-899059.hostingersite.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image003-e1726606072123.jpg\",\"contentUrl\":\"https:\\\/\\\/lightgoldenrodyellow-dugong-899059.hostingersite.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image003-e1726606072123.jpg\",\"width\":640,\"height\":405,\"caption\":\"racoes e forragens castanheira\"},\"image\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/racoeseforragenscastanheira\",\"https:\\\/\\\/www.instagram.com\\\/racoes_e_forragens_castanheira\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abano em palha com cabo em madeira - racoes e forragens castanheira","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/abano-em-palha-com-cabo-em-madeira\/","og_locale":"en_GB","og_type":"article","og_title":"Abano em palha com cabo em madeira - racoes e forragens castanheira","og_description":"O Abano em Palha com Cabo em Madeira \u00e9 a ferramenta perfeita para quem busca conforto e praticidade na hora de espantar o calor ou auxiliar em ambientes mais quentes. Com um design r\u00fastico e natural, o abano possui um cabo em madeira resistente e confort\u00e1vel para manuseio, proporcionando durabilidade e facilidade no uso.","og_url":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/abano-em-palha-com-cabo-em-madeira\/","og_site_name":"racoes e forragens castanheira","article_publisher":"https:\/\/www.facebook.com\/racoeseforragenscastanheira","article_modified_time":"2026-03-25T16:15:20+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-78.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/abano-em-palha-com-cabo-em-madeira\/","url":"https:\/\/racoeseforragenscastanheira.com\/produto\/abano-em-palha-com-cabo-em-madeira\/","name":"Abano em palha com cabo em madeira - racoes e forragens castanheira","isPartOf":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/abano-em-palha-com-cabo-em-madeira\/#primaryimage"},"image":{"@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/abano-em-palha-com-cabo-em-madeira\/#primaryimage"},"thumbnailUrl":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-78.png","datePublished":"2024-10-21T14:33:21+00:00","dateModified":"2026-03-25T16:15:20+00:00","breadcrumb":{"@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/abano-em-palha-com-cabo-em-madeira\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/racoeseforragenscastanheira.com\/produto\/abano-em-palha-com-cabo-em-madeira\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/abano-em-palha-com-cabo-em-madeira\/#primaryimage","url":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-78.png","contentUrl":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-78.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/abano-em-palha-com-cabo-em-madeira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/racoeseforragenscastanheira.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/racoeseforragenscastanheira.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Abano em palha com cabo em madeira"}]},{"@type":"WebSite","@id":"https:\/\/racoeseforragenscastanheira.com\/#website","url":"https:\/\/racoeseforragenscastanheira.com\/","name":"racoes e forragens castanheira","description":"","publisher":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/racoeseforragenscastanheira.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/racoeseforragenscastanheira.com\/#organization","name":"racoes e forragens castanheira","url":"https:\/\/racoeseforragenscastanheira.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/racoeseforragenscastanheira.com\/#\/schema\/logo\/image\/","url":"https:\/\/lightgoldenrodyellow-dugong-899059.hostingersite.com\/wp-content\/uploads\/2025\/01\/image003-e1726606072123.jpg","contentUrl":"https:\/\/lightgoldenrodyellow-dugong-899059.hostingersite.com\/wp-content\/uploads\/2025\/01\/image003-e1726606072123.jpg","width":640,"height":405,"caption":"racoes e forragens castanheira"},"image":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/racoeseforragenscastanheira","https:\/\/www.instagram.com\/racoes_e_forragens_castanheira\/"]}]}},"_links":{"self":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product\/835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/comments?post=835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/media\/836"}],"wp:attachment":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/media?parent=835"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_brand?post=835"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_cat?post=835"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_tag?post=835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}