{"id":818,"date":"2024-10-21T14:09:36","date_gmt":"2024-10-21T14:09:36","guid":{"rendered":"https:\/\/racoeseforragenscastanheira.com\/?post_type=product&#038;p=818"},"modified":"2026-05-05T15:36:20","modified_gmt":"2026-05-05T15:36:20","slug":"inseticida-decis-jardim-500ml","status":"publish","type":"product","link":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/inseticida-decis-jardim-500ml\/","title":{"rendered":"Inseticida Decis  Jardim 500ML"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div class=\"tabs laberTabs\">\n<div id=\"tab-content\" class=\"tab-content\">\n<div id=\"description\" class=\"tab-pane fade in active\">\n<div class=\"product-description\">Decis Garden AL Bayer spray inseticida para jardim \u00e0 base de deltametrina pronto para uso ideal para todas as plantas ornamentais, 750 ml. pulg\u00f5es mosca-branca ger\u00e2nio larvas da mariposa barata &#8211; Oziorrinco Ingrediente ativo &#8211; deltametrina 0,0075 g de L MODO DE USAR: \u00c9 pulverizado a cerca de 30 por 40 cm da planta. Repita o tratamento &#8211; se necess\u00e1rio &#8211; ap\u00f3s 7 dias.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<section class=\"laberCategoryPro\">\n<div class=\"laberthemes\">\n<div class=\"Categoryproducts laberProductGrid\">\n<div class=\"title_block\"><\/div>\n<\/div>\n<\/div>\n<\/section>","protected":false},"featured_media":819,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":{"0":"post-818","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-horta-jardim","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inseticida Decis Jardim 500ML - racoes e forragens castanheira<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/racoeseforragenscastanheira.com\/en\/product\/inseticida-decis-jardim-500ml\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inseticida Decis Jardim 500ML - racoes e forragens castanheira\" \/>\n<meta property=\"og:description\" content=\"Decis Garden AL Bayer spray inseticida para jardim \u00e0 base de deltametrina pronto para uso ideal para todas as plantas ornamentais, 750 ml. pulg\u00f5es mosca-branca ger\u00e2nio larvas da mariposa barata - Oziorrinco Ingrediente ativo - deltametrina 0,0075 g de L MODO DE USAR: \u00c9 pulverizado a cerca de 30 por 40 cm da planta. Repita o tratamento - se necess\u00e1rio - ap\u00f3s 7 dias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/racoeseforragenscastanheira.com\/en\/product\/inseticida-decis-jardim-500ml\/\" \/>\n<meta property=\"og:site_name\" content=\"racoes e forragens castanheira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/racoeseforragenscastanheira\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T15:36:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-70.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/inseticida-decis-jardim-500ml\\\/\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/inseticida-decis-jardim-500ml\\\/\",\"name\":\"Inseticida Decis Jardim 500ML - racoes e forragens castanheira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/inseticida-decis-jardim-500ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/inseticida-decis-jardim-500ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Copia-de-Design-sem-nome-70.png\",\"datePublished\":\"2024-10-21T14:09:36+00:00\",\"dateModified\":\"2026-05-05T15:36:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/inseticida-decis-jardim-500ml\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/inseticida-decis-jardim-500ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/inseticida-decis-jardim-500ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Copia-de-Design-sem-nome-70.png\",\"contentUrl\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Copia-de-Design-sem-nome-70.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/inseticida-decis-jardim-500ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inseticida Decis Jardim 500ML\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#website\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\",\"name\":\"racoes e forragens castanheira\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#organization\",\"name\":\"racoes e forragens castanheira\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lightgoldenrodyellow-dugong-899059.hostingersite.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image003-e1726606072123.jpg\",\"contentUrl\":\"https:\\\/\\\/lightgoldenrodyellow-dugong-899059.hostingersite.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image003-e1726606072123.jpg\",\"width\":640,\"height\":405,\"caption\":\"racoes e forragens castanheira\"},\"image\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/racoeseforragenscastanheira\",\"https:\\\/\\\/www.instagram.com\\\/racoes_e_forragens_castanheira\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inseticida Decis Jardim 500ML - racoes e forragens castanheira","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/inseticida-decis-jardim-500ml\/","og_locale":"en_GB","og_type":"article","og_title":"Inseticida Decis Jardim 500ML - racoes e forragens castanheira","og_description":"Decis Garden AL Bayer spray inseticida para jardim \u00e0 base de deltametrina pronto para uso ideal para todas as plantas ornamentais, 750 ml. pulg\u00f5es mosca-branca ger\u00e2nio larvas da mariposa barata - Oziorrinco Ingrediente ativo - deltametrina 0,0075 g de L MODO DE USAR: \u00c9 pulverizado a cerca de 30 por 40 cm da planta. Repita o tratamento - se necess\u00e1rio - ap\u00f3s 7 dias.","og_url":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/inseticida-decis-jardim-500ml\/","og_site_name":"racoes e forragens castanheira","article_publisher":"https:\/\/www.facebook.com\/racoeseforragenscastanheira","article_modified_time":"2026-05-05T15:36:20+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-70.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/inseticida-decis-jardim-500ml\/","url":"https:\/\/racoeseforragenscastanheira.com\/produto\/inseticida-decis-jardim-500ml\/","name":"Inseticida Decis Jardim 500ML - racoes e forragens castanheira","isPartOf":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/inseticida-decis-jardim-500ml\/#primaryimage"},"image":{"@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/inseticida-decis-jardim-500ml\/#primaryimage"},"thumbnailUrl":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-70.png","datePublished":"2024-10-21T14:09:36+00:00","dateModified":"2026-05-05T15:36:20+00:00","breadcrumb":{"@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/inseticida-decis-jardim-500ml\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/racoeseforragenscastanheira.com\/produto\/inseticida-decis-jardim-500ml\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/inseticida-decis-jardim-500ml\/#primaryimage","url":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-70.png","contentUrl":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/10\/Copia-de-Design-sem-nome-70.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/inseticida-decis-jardim-500ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/racoeseforragenscastanheira.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/racoeseforragenscastanheira.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Inseticida Decis Jardim 500ML"}]},{"@type":"WebSite","@id":"https:\/\/racoeseforragenscastanheira.com\/#website","url":"https:\/\/racoeseforragenscastanheira.com\/","name":"racoes e forragens castanheira","description":"","publisher":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/racoeseforragenscastanheira.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/racoeseforragenscastanheira.com\/#organization","name":"racoes e forragens castanheira","url":"https:\/\/racoeseforragenscastanheira.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/racoeseforragenscastanheira.com\/#\/schema\/logo\/image\/","url":"https:\/\/lightgoldenrodyellow-dugong-899059.hostingersite.com\/wp-content\/uploads\/2025\/01\/image003-e1726606072123.jpg","contentUrl":"https:\/\/lightgoldenrodyellow-dugong-899059.hostingersite.com\/wp-content\/uploads\/2025\/01\/image003-e1726606072123.jpg","width":640,"height":405,"caption":"racoes e forragens castanheira"},"image":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/racoeseforragenscastanheira","https:\/\/www.instagram.com\/racoes_e_forragens_castanheira\/"]}]}},"_links":{"self":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product\/818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/comments?post=818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/media\/819"}],"wp:attachment":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/media?parent=818"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_brand?post=818"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_cat?post=818"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_tag?post=818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}