{"id":1242,"date":"2024-11-05T09:18:32","date_gmt":"2024-11-05T09:18:32","guid":{"rendered":"https:\/\/racoeseforragenscastanheira.com\/?post_type=product&#038;p=1242"},"modified":"2025-11-24T16:19:29","modified_gmt":"2025-11-24T16:19:29","slug":"cipergen-1lt-bioplagen","status":"publish","type":"product","link":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/cipergen-1lt-bioplagen\/","title":{"rendered":"Cipergen 1Lt BIOPLAGEN"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><b>CIPERGEN \u00ae \u00e9 um inseticida do tipo piretr\u00f3ide, com atividade por contato e ingest\u00e3o em um amplo espectro de insetos. \u00c9 caracterizada por seu acentuado efeito de choque (knockdown) e grande atividade em doses baixas. \u00c9 indicado para o controle de insetos, tais como: moscas, mosquitos, pulgas, carrapatos, vespas, \u00e1caros, etc., em animais, aves, canil, bem como na desinfec\u00e7\u00e3o do transporte de animais e de outros animais. Tamb\u00e9m \u00e9 usado em matadouros, salas de corte e na ind\u00fastria de alimentos em geral<\/b><\/p>","protected":false},"featured_media":1243,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[24],"product_tag":[],"class_list":{"0":"post-1242","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pecuaria","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cipergen 1Lt BIOPLAGEN - racoes e forragens castanheira<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/racoeseforragenscastanheira.com\/en\/product\/cipergen-1lt-bioplagen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cipergen 1Lt BIOPLAGEN - racoes e forragens castanheira\" \/>\n<meta property=\"og:description\" content=\"CIPERGEN \u00ae \u00e9 um inseticida do tipo piretr\u00f3ide, com atividade por contato e ingest\u00e3o em um amplo espectro de insetos. \u00c9 caracterizada por seu acentuado efeito de choque (knockdown) e grande atividade em doses baixas. \u00c9 indicado para o controle de insetos, tais como: moscas, mosquitos, pulgas, carrapatos, vespas, \u00e1caros, etc., em animais, aves, canil, bem como na desinfec\u00e7\u00e3o do transporte de animais e de outros animais. Tamb\u00e9m \u00e9 usado em matadouros, salas de corte e na ind\u00fastria de alimentos em geral\" \/>\n<meta property=\"og:url\" content=\"https:\/\/racoeseforragenscastanheira.com\/en\/product\/cipergen-1lt-bioplagen\/\" \/>\n<meta property=\"og:site_name\" content=\"racoes e forragens castanheira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/racoeseforragenscastanheira\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-24T16:19:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/11\/Copia-de-Design-sem-nome-2024-11-05T091804.582.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/cipergen-1lt-bioplagen\\\/\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/cipergen-1lt-bioplagen\\\/\",\"name\":\"Cipergen 1Lt BIOPLAGEN - racoes e forragens castanheira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/cipergen-1lt-bioplagen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/cipergen-1lt-bioplagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Copia-de-Design-sem-nome-2024-11-05T091804.582.png\",\"datePublished\":\"2024-11-05T09:18:32+00:00\",\"dateModified\":\"2025-11-24T16:19:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/cipergen-1lt-bioplagen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/cipergen-1lt-bioplagen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/cipergen-1lt-bioplagen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Copia-de-Design-sem-nome-2024-11-05T091804.582.png\",\"contentUrl\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Copia-de-Design-sem-nome-2024-11-05T091804.582.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/produto\\\/cipergen-1lt-bioplagen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cipergen 1Lt BIOPLAGEN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#website\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\",\"name\":\"racoes e forragens castanheira\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#organization\",\"name\":\"racoes e forragens castanheira\",\"url\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lightgoldenrodyellow-dugong-899059.hostingersite.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image003-e1726606072123.jpg\",\"contentUrl\":\"https:\\\/\\\/lightgoldenrodyellow-dugong-899059.hostingersite.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/image003-e1726606072123.jpg\",\"width\":640,\"height\":405,\"caption\":\"racoes e forragens castanheira\"},\"image\":{\"@id\":\"https:\\\/\\\/racoeseforragenscastanheira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/racoeseforragenscastanheira\",\"https:\\\/\\\/www.instagram.com\\\/racoes_e_forragens_castanheira\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cipergen 1Lt BIOPLAGEN - racoes e forragens castanheira","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/cipergen-1lt-bioplagen\/","og_locale":"en_GB","og_type":"article","og_title":"Cipergen 1Lt BIOPLAGEN - racoes e forragens castanheira","og_description":"CIPERGEN \u00ae \u00e9 um inseticida do tipo piretr\u00f3ide, com atividade por contato e ingest\u00e3o em um amplo espectro de insetos. \u00c9 caracterizada por seu acentuado efeito de choque (knockdown) e grande atividade em doses baixas. \u00c9 indicado para o controle de insetos, tais como: moscas, mosquitos, pulgas, carrapatos, vespas, \u00e1caros, etc., em animais, aves, canil, bem como na desinfec\u00e7\u00e3o do transporte de animais e de outros animais. Tamb\u00e9m \u00e9 usado em matadouros, salas de corte e na ind\u00fastria de alimentos em geral","og_url":"https:\/\/racoeseforragenscastanheira.com\/en\/product\/cipergen-1lt-bioplagen\/","og_site_name":"racoes e forragens castanheira","article_publisher":"https:\/\/www.facebook.com\/racoeseforragenscastanheira","article_modified_time":"2025-11-24T16:19:29+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/11\/Copia-de-Design-sem-nome-2024-11-05T091804.582.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/cipergen-1lt-bioplagen\/","url":"https:\/\/racoeseforragenscastanheira.com\/produto\/cipergen-1lt-bioplagen\/","name":"Cipergen 1Lt BIOPLAGEN - racoes e forragens castanheira","isPartOf":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/cipergen-1lt-bioplagen\/#primaryimage"},"image":{"@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/cipergen-1lt-bioplagen\/#primaryimage"},"thumbnailUrl":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/11\/Copia-de-Design-sem-nome-2024-11-05T091804.582.png","datePublished":"2024-11-05T09:18:32+00:00","dateModified":"2025-11-24T16:19:29+00:00","breadcrumb":{"@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/cipergen-1lt-bioplagen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/racoeseforragenscastanheira.com\/produto\/cipergen-1lt-bioplagen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/cipergen-1lt-bioplagen\/#primaryimage","url":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/11\/Copia-de-Design-sem-nome-2024-11-05T091804.582.png","contentUrl":"https:\/\/racoeseforragenscastanheira.com\/wp-content\/uploads\/2024\/11\/Copia-de-Design-sem-nome-2024-11-05T091804.582.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/racoeseforragenscastanheira.com\/produto\/cipergen-1lt-bioplagen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/racoeseforragenscastanheira.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/racoeseforragenscastanheira.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Cipergen 1Lt BIOPLAGEN"}]},{"@type":"WebSite","@id":"https:\/\/racoeseforragenscastanheira.com\/#website","url":"https:\/\/racoeseforragenscastanheira.com\/","name":"racoes e forragens castanheira","description":"","publisher":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/racoeseforragenscastanheira.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/racoeseforragenscastanheira.com\/#organization","name":"racoes e forragens castanheira","url":"https:\/\/racoeseforragenscastanheira.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/racoeseforragenscastanheira.com\/#\/schema\/logo\/image\/","url":"https:\/\/lightgoldenrodyellow-dugong-899059.hostingersite.com\/wp-content\/uploads\/2025\/01\/image003-e1726606072123.jpg","contentUrl":"https:\/\/lightgoldenrodyellow-dugong-899059.hostingersite.com\/wp-content\/uploads\/2025\/01\/image003-e1726606072123.jpg","width":640,"height":405,"caption":"racoes e forragens castanheira"},"image":{"@id":"https:\/\/racoeseforragenscastanheira.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/racoeseforragenscastanheira","https:\/\/www.instagram.com\/racoes_e_forragens_castanheira\/"]}]}},"_links":{"self":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product\/1242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/comments?post=1242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/media\/1243"}],"wp:attachment":[{"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/media?parent=1242"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_brand?post=1242"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_cat?post=1242"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/racoeseforragenscastanheira.com\/en\/wp-json\/wp\/v2\/product_tag?post=1242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}